{"id":31694,"date":"2020-12-09T11:53:49","date_gmt":"2020-12-09T10:53:49","guid":{"rendered":"https:\/\/www.oodrive.com\/?p=31694"},"modified":"2026-08-18T09:39:10","modified_gmt":"2026-08-18T09:39:10","slug":"histoire-sauvegarde","status":"publish","type":"post","link":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/","title":{"rendered":"En bref : l&rsquo;histoire de la sauvegarde"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">La sauvegarde<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9finition : Copie de s\u00e9curit\u00e9 destin\u00e9e \u00e0 pr\u00e9server des donn\u00e9es mises en m\u00e9moire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es. L\u00e0 o\u00f9 certains y voient la nostalgie des cassettes et autres disquettes, elle est aujourd\u2019hui synonyme de protection, de d\u00e9fense et de s\u00e9curit\u00e9 dans le domaine de l\u2019informatique.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais son histoire est plus ancienne, car elle remonte \u00e0 l\u2019invention de l\u2019\u00e9criture aux environs de 4000 av JC. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, ce sont les tablettes d\u2019argile et le papyrus qui ont r\u00e9colt\u00e9 en premier des informations dans l\u2019objectif de les conserver.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et, comme pour chaque invention, c\u2019est lorsque le progr\u00e8s technique est au plus haut que l\u2019\u00e9volution est la plus forte. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Au XXe si\u00e8cle, les supports de sauvegarde s\u2019enchainent, dans un format toujours plus r\u00e9duit. Associ\u00e9e aux apparitions du num\u00e9rique, puis du web, la course \u00e0 la performance m\u00e8nera \u00e0 la technologie du \u201ccloud\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si l\u2019avenir dans ce domaine peut parfois sembler complexe ; notamment face aux probl\u00e8mes de cybercriminalit\u00e9 dont l\u2019impact \u00e9conomique est lourd pour les entreprises ; il demeure serein. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En effet, l\u2019apparition r\u00e9cente d\u2019<a href=\"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde\/sauvegarde-donnees\/logiciel-sauvegarde-proteger-donnees-entreprises\/\">outils de sauvegarde de donn\u00e9es<\/a> performants peut rassurer les entrepreneurs.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gr\u00e2ce \u00e0 des infrastructures num\u00e9riques all\u00e9g\u00e9es, et des reprises d\u2019activit\u00e9s quasi-instantan\u00e9es en cas d\u2019attaques, les op\u00e9rations des diff\u00e9rents secteurs d\u2019activit\u00e9s peuvent se maintenir, en toute s\u00e9r\u00e9nit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mais \u00e7a n\u2019a pas toujours \u00e9t\u00e9 le cas ! D\u00e9couvrez en r\u00e9sum\u00e9, l\u2019histoire de la sauvegarde, et des supports de stockage qui l\u2019ont accompagn\u00e9e.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" src=\"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2020\/12\/frise-save.jpg\" alt=\"\" class=\"wp-image-31695\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Les supports d\u2019information se sont d\u00e9multipli\u00e9s tout au long de l\u2019histoire de la sauvegarde de donn\u00e9es. Elle peut s\u2019expliquer par notre souhait, en tant qu\u2019humain, de sauvegarder et transmettre des \u00e9l\u00e9ments structurants d\u2019information, ou m\u00eame de notre histoire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De nos jours, la p\u00e9rennisation des donn\u00e9es est primordiale pour nos entreprises. Face \u00e0 la cybercriminalit\u00e9, des technologies comme Oodrive Save existent. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Elles innovent pour allier r\u00e9activit\u00e9, optimisation et s\u00e9r\u00e9nit\u00e9, et permettre une plus grande agilit\u00e9 dans la reprise d\u2019activit\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Par ailleurs, si la sauvegarde est une \u00e9tape importante dans la gestion des donn\u00e9es d\u2019une entreprise, elle n\u2019est pas la seule ! <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un document passe effet par de nombreuses \u00e9tapes depuis sa cr\u00e9ation jusqu\u2019\u00e0 sa sauvegarde. Son \u00e9dition son partage, mais aussi son organisation, sa diffusion, ou encore sa signature. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Et si l\u2019ensemble de ces fonctionnalit\u00e9s majeures \u00e9taient regroup\u00e9es en un socle commun, permettant de g\u00e9rer en tous points ses contenus ?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oodrive Save, notre <a href=\"https:\/\/pp.oodrive-save.com\/fr\/produits\/oodrive-save\/\">solution de sauvegarde<\/a> s\u2019int\u00e8gre \u00e0 la plateforme oodrive. Un d\u2019un environnement de travail de confiance, o\u00f9 la s\u00e9r\u00e9nit\u00e9 r\u00e8gne, et permet aux projets strat\u00e9giques de se r\u00e9aliser. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ce module vous lib\u00e8re des probl\u00e9matiques de s\u00e9curit\u00e9 et vous permet de vous recentrer sur votre c\u0153ur d\u2019activit\u00e9.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La sauvegarde D\u00e9finition : Copie de s\u00e9curit\u00e9 destin\u00e9e \u00e0 pr\u00e9server des donn\u00e9es mises en m\u00e9moire. La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es. L\u00e0 o\u00f9 certains y voient la nostalgie des cassettes et autres disquettes, elle est aujourd\u2019hui synonyme de protection, de d\u00e9fense et de s\u00e9curit\u00e9 dans le domaine de [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":31701,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[25],"class_list":["post-31694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sauvegarde-donnees"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>En bref : l&#039;histoire de la sauvegarde - Oodriv Save<\/title>\n<meta name=\"description\" content=\"La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En bref : l&#039;histoire de la sauvegarde - Oodriv Save\" \/>\n<meta property=\"og:description\" content=\"La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/\" \/>\n<meta property=\"og:site_name\" content=\"Oodriv Save\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-09T10:53:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-08-18T09:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2020\/12\/avant-save-bandeau-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"L&#039;\u00e9quipe Oodrive Save\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L&#039;\u00e9quipe Oodrive Save\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/\"},\"author\":{\"name\":\"L'\u00e9quipe Oodrive Save\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#\\\/schema\\\/person\\\/4f56103b9131d9c389e388b4c268f908\"},\"headline\":\"En bref : l&rsquo;histoire de la sauvegarde\",\"datePublished\":\"2020-12-09T10:53:49+00:00\",\"dateModified\":\"2026-08-18T09:39:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/\"},\"wordCount\":522,\"publisher\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/avant-save-bandeau-1.jpg\",\"articleSection\":[\"Sauvegarde des donn\u00e9es\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/\",\"url\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/\",\"name\":\"En bref : l'histoire de la sauvegarde - Oodriv Save\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/avant-save-bandeau-1.jpg\",\"datePublished\":\"2020-12-09T10:53:49+00:00\",\"dateModified\":\"2026-08-18T09:39:10+00:00\",\"description\":\"La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/avant-save-bandeau-1.jpg\",\"contentUrl\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/avant-save-bandeau-1.jpg\",\"width\":1000,\"height\":500},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/blog\\\/sauvegarde-donnees\\\/histoire-sauvegarde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En bref : l&#8217;histoire de la sauvegarde\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/\",\"name\":\"Oodriv Save\",\"description\":\"S\u00e9curisez les donn\u00e9es critiques de votre organisation en les sauvegardant dans un cloud souverain de confiance et restaurez-les en toute simplicit\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#organization\",\"name\":\"Oodriv Save\",\"url\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/oodrive-save.svg\",\"contentUrl\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/oodrive-save.svg\",\"width\":130,\"height\":16,\"caption\":\"Oodriv Save\"},\"image\":{\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/#\\\/schema\\\/person\\\/4f56103b9131d9c389e388b4c268f908\",\"name\":\"L'\u00e9quipe Oodrive Save\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/favicon-oodrive-save-150x150.png\",\"url\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/favicon-oodrive-save-150x150.png\",\"contentUrl\":\"https:\\\/\\\/pp.oodrive-save.com\\\/wp-content\\\/uploads\\\/2026\\\/07\\\/favicon-oodrive-save-150x150.png\",\"caption\":\"L'\u00e9quipe Oodrive Save\"},\"url\":\"https:\\\/\\\/pp.oodrive-save.com\\\/fr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En bref : l'histoire de la sauvegarde - Oodriv Save","description":"La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"En bref : l'histoire de la sauvegarde - Oodriv Save","og_description":"La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es.","og_url":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/","og_site_name":"Oodriv Save","article_published_time":"2020-12-09T10:53:49+00:00","article_modified_time":"2026-08-18T09:39:10+00:00","og_image":[{"width":1000,"height":500,"url":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2020\/12\/avant-save-bandeau-1.jpg","type":"image\/jpeg"}],"author":"L'\u00e9quipe Oodrive Save","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"L'\u00e9quipe Oodrive Save","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/#article","isPartOf":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/"},"author":{"name":"L'\u00e9quipe Oodrive Save","@id":"https:\/\/pp.oodrive-save.com\/fr\/#\/schema\/person\/4f56103b9131d9c389e388b4c268f908"},"headline":"En bref : l&rsquo;histoire de la sauvegarde","datePublished":"2020-12-09T10:53:49+00:00","dateModified":"2026-08-18T09:39:10+00:00","mainEntityOfPage":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/"},"wordCount":522,"publisher":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/#organization"},"image":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/#primaryimage"},"thumbnailUrl":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2020\/12\/avant-save-bandeau-1.jpg","articleSection":["Sauvegarde des donn\u00e9es"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/","url":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/","name":"En bref : l'histoire de la sauvegarde - Oodriv Save","isPartOf":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/#primaryimage"},"image":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/#primaryimage"},"thumbnailUrl":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2020\/12\/avant-save-bandeau-1.jpg","datePublished":"2020-12-09T10:53:49+00:00","dateModified":"2026-08-18T09:39:10+00:00","description":"La sauvegarde prend son sens depuis les premiers besoins de stockage de donn\u00e9es.","breadcrumb":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/#primaryimage","url":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2020\/12\/avant-save-bandeau-1.jpg","contentUrl":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2020\/12\/avant-save-bandeau-1.jpg","width":1000,"height":500},{"@type":"BreadcrumbList","@id":"https:\/\/pp.oodrive-save.com\/fr\/blog\/sauvegarde-donnees\/histoire-sauvegarde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/pp.oodrive-save.com\/fr\/"},{"@type":"ListItem","position":2,"name":"En bref : l&#8217;histoire de la sauvegarde"}]},{"@type":"WebSite","@id":"https:\/\/pp.oodrive-save.com\/fr\/#website","url":"https:\/\/pp.oodrive-save.com\/fr\/","name":"Oodriv Save","description":"S\u00e9curisez les donn\u00e9es critiques de votre organisation en les sauvegardant dans un cloud souverain de confiance et restaurez-les en toute simplicit\u00e9","publisher":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pp.oodrive-save.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/pp.oodrive-save.com\/fr\/#organization","name":"Oodriv Save","url":"https:\/\/pp.oodrive-save.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pp.oodrive-save.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2026\/07\/oodrive-save.svg","contentUrl":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2026\/07\/oodrive-save.svg","width":130,"height":16,"caption":"Oodriv Save"},"image":{"@id":"https:\/\/pp.oodrive-save.com\/fr\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pp.oodrive-save.com\/fr\/#\/schema\/person\/4f56103b9131d9c389e388b4c268f908","name":"L'\u00e9quipe Oodrive Save","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2026\/07\/favicon-oodrive-save-150x150.png","url":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2026\/07\/favicon-oodrive-save-150x150.png","contentUrl":"https:\/\/pp.oodrive-save.com\/wp-content\/uploads\/2026\/07\/favicon-oodrive-save-150x150.png","caption":"L'\u00e9quipe Oodrive Save"},"url":"https:\/\/pp.oodrive-save.com\/fr\/"}]}},"_links":{"self":[{"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/posts\/31694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/comments?post=31694"}],"version-history":[{"count":1,"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/posts\/31694\/revisions"}],"predecessor-version":[{"id":8109393,"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/posts\/31694\/revisions\/8109393"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/media\/31701"}],"wp:attachment":[{"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/media?parent=31694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pp.oodrive-save.com\/fr\/wp-json\/wp\/v2\/categories?post=31694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}